{"id":13091,"date":"2024-03-02T17:38:23","date_gmt":"2024-03-02T10:38:23","guid":{"rendered":"https:\/\/www.kpi.co.th\/kpi\/garage\/%e0%b8%aa%e0%b8%b8%e0%b8%a3%e0%b8%b2%e0%b8%a9%e0%b8%8e%e0%b8%a3%e0%b9%8c%e0%b8%ae%e0%b8%ad%e0%b8%99%e0%b8%94%e0%b9%89%e0%b8%b2-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a1%e0%b8%9a-2\/"},"modified":"2025-09-11T10:37:09","modified_gmt":"2025-09-11T03:37:09","slug":"%e0%b8%aa%e0%b8%b8%e0%b8%a3%e0%b8%b2%e0%b8%a9%e0%b8%8e%e0%b8%a3%e0%b9%8c%e0%b8%ae%e0%b8%ad%e0%b8%99%e0%b8%94%e0%b9%89%e0%b8%b2-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a1%e0%b8%9a%e0%b8%b4","status":"publish","type":"garage","link":"https:\/\/www.kpi.co.th\/kpi\/garage\/%e0%b8%aa%e0%b8%b8%e0%b8%a3%e0%b8%b2%e0%b8%a9%e0%b8%8e%e0%b8%a3%e0%b9%8c%e0%b8%ae%e0%b8%ad%e0%b8%99%e0%b8%94%e0%b9%89%e0%b8%b2-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a1%e0%b8%9a%e0%b8%b4\/","title":{"rendered":"\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32 \u0e2d\u0e2d\u0e42\u0e15\u0e42\u0e21\u0e1a\u0e34\u0e25"},"content":{"rendered":"\n<p>34\/4 \u0e2b\u0e21\u0e39\u0e48 4 \u0e16.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e27\u0e34\u0e16\u0e35 \u0e15.\u0e1a\u0e32\u0e07\u0e01\u0e38\u0e49\u0e07 \u0e2d.\u0e40\u0e21\u0e37\u0e2d\u0e07 \n\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 84000<\/p>\n\n","protected":false},"featured_media":0,"template":"","car_type":[],"garage_type":[261,105],"car_brand":[60],"class_list":["post-13091","garage","type-garage","status-publish","hentry","garage_type-all-garage-servicecenter-autoglass","garage_type-service-center","car_brand-honda"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32 \u0e2d\u0e2d\u0e42\u0e15\u0e42\u0e21\u0e1a\u0e34\u0e25 - KPI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kpi.co.th\/kpi\/garage\/%e0%b8%aa%e0%b8%b8%e0%b8%a3%e0%b8%b2%e0%b8%a9%e0%b8%8e%e0%b8%a3%e0%b9%8c%e0%b8%ae%e0%b8%ad%e0%b8%99%e0%b8%94%e0%b9%89%e0%b8%b2-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a1%e0%b8%9a%e0%b8%b4\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32 \u0e2d\u0e2d\u0e42\u0e15\u0e42\u0e21\u0e1a\u0e34\u0e25 - KPI\" \/>\n<meta property=\"og:description\" content=\"34\/4 \u0e2b\u0e21\u0e39\u0e48 4 \u0e16.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e27\u0e34\u0e16\u0e35 \u0e15.\u0e1a\u0e32\u0e07\u0e01\u0e38\u0e49\u0e07 \u0e2d.\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kpi.co.th\/kpi\/garage\/%e0%b8%aa%e0%b8%b8%e0%b8%a3%e0%b8%b2%e0%b8%a9%e0%b8%8e%e0%b8%a3%e0%b9%8c%e0%b8%ae%e0%b8%ad%e0%b8%99%e0%b8%94%e0%b9%89%e0%b8%b2-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a1%e0%b8%9a%e0%b8%b4\/\" \/>\n<meta property=\"og:site_name\" content=\"KPI\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-11T03:37:09+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 \u0e19\u0e32\u0e17\u0e35\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/garage\\\/%e0%b8%aa%e0%b8%b8%e0%b8%a3%e0%b8%b2%e0%b8%a9%e0%b8%8e%e0%b8%a3%e0%b9%8c%e0%b8%ae%e0%b8%ad%e0%b8%99%e0%b8%94%e0%b9%89%e0%b8%b2-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a1%e0%b8%9a%e0%b8%b4\\\/\",\"url\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/garage\\\/%e0%b8%aa%e0%b8%b8%e0%b8%a3%e0%b8%b2%e0%b8%a9%e0%b8%8e%e0%b8%a3%e0%b9%8c%e0%b8%ae%e0%b8%ad%e0%b8%99%e0%b8%94%e0%b9%89%e0%b8%b2-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a1%e0%b8%9a%e0%b8%b4\\\/\",\"name\":\"\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32 \u0e2d\u0e2d\u0e42\u0e15\u0e42\u0e21\u0e1a\u0e34\u0e25 - KPI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/#website\"},\"datePublished\":\"2024-03-02T10:38:23+00:00\",\"dateModified\":\"2025-09-11T03:37:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/garage\\\/%e0%b8%aa%e0%b8%b8%e0%b8%a3%e0%b8%b2%e0%b8%a9%e0%b8%8e%e0%b8%a3%e0%b9%8c%e0%b8%ae%e0%b8%ad%e0%b8%99%e0%b8%94%e0%b9%89%e0%b8%b2-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a1%e0%b8%9a%e0%b8%b4\\\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/garage\\\/%e0%b8%aa%e0%b8%b8%e0%b8%a3%e0%b8%b2%e0%b8%a9%e0%b8%8e%e0%b8%a3%e0%b9%8c%e0%b8%ae%e0%b8%ad%e0%b8%99%e0%b8%94%e0%b9%89%e0%b8%b2-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a1%e0%b8%9a%e0%b8%b4\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/garage\\\/%e0%b8%aa%e0%b8%b8%e0%b8%a3%e0%b8%b2%e0%b8%a9%e0%b8%8e%e0%b8%a3%e0%b9%8c%e0%b8%ae%e0%b8%ad%e0%b8%99%e0%b8%94%e0%b9%89%e0%b8%b2-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a1%e0%b8%9a%e0%b8%b4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32 \u0e2d\u0e2d\u0e42\u0e15\u0e42\u0e21\u0e1a\u0e34\u0e25\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/#website\",\"url\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/\",\"name\":\"KPI\",\"description\":\"KPI\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32 \u0e2d\u0e2d\u0e42\u0e15\u0e42\u0e21\u0e1a\u0e34\u0e25 - KPI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kpi.co.th\/kpi\/garage\/%e0%b8%aa%e0%b8%b8%e0%b8%a3%e0%b8%b2%e0%b8%a9%e0%b8%8e%e0%b8%a3%e0%b9%8c%e0%b8%ae%e0%b8%ad%e0%b8%99%e0%b8%94%e0%b9%89%e0%b8%b2-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a1%e0%b8%9a%e0%b8%b4\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32 \u0e2d\u0e2d\u0e42\u0e15\u0e42\u0e21\u0e1a\u0e34\u0e25 - KPI","og_description":"34\/4 \u0e2b\u0e21\u0e39\u0e48 4 \u0e16.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e27\u0e34\u0e16\u0e35 \u0e15.\u0e1a\u0e32\u0e07\u0e01\u0e38\u0e49\u0e07 \u0e2d.\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19 [&hellip;]","og_url":"https:\/\/www.kpi.co.th\/kpi\/garage\/%e0%b8%aa%e0%b8%b8%e0%b8%a3%e0%b8%b2%e0%b8%a9%e0%b8%8e%e0%b8%a3%e0%b9%8c%e0%b8%ae%e0%b8%ad%e0%b8%99%e0%b8%94%e0%b9%89%e0%b8%b2-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a1%e0%b8%9a%e0%b8%b4\/","og_site_name":"KPI","article_modified_time":"2025-09-11T03:37:09+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 \u0e19\u0e32\u0e17\u0e35"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.kpi.co.th\/kpi\/garage\/%e0%b8%aa%e0%b8%b8%e0%b8%a3%e0%b8%b2%e0%b8%a9%e0%b8%8e%e0%b8%a3%e0%b9%8c%e0%b8%ae%e0%b8%ad%e0%b8%99%e0%b8%94%e0%b9%89%e0%b8%b2-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a1%e0%b8%9a%e0%b8%b4\/","url":"https:\/\/www.kpi.co.th\/kpi\/garage\/%e0%b8%aa%e0%b8%b8%e0%b8%a3%e0%b8%b2%e0%b8%a9%e0%b8%8e%e0%b8%a3%e0%b9%8c%e0%b8%ae%e0%b8%ad%e0%b8%99%e0%b8%94%e0%b9%89%e0%b8%b2-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a1%e0%b8%9a%e0%b8%b4\/","name":"\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32 \u0e2d\u0e2d\u0e42\u0e15\u0e42\u0e21\u0e1a\u0e34\u0e25 - KPI","isPartOf":{"@id":"https:\/\/www.kpi.co.th\/kpi\/#website"},"datePublished":"2024-03-02T10:38:23+00:00","dateModified":"2025-09-11T03:37:09+00:00","breadcrumb":{"@id":"https:\/\/www.kpi.co.th\/kpi\/garage\/%e0%b8%aa%e0%b8%b8%e0%b8%a3%e0%b8%b2%e0%b8%a9%e0%b8%8e%e0%b8%a3%e0%b9%8c%e0%b8%ae%e0%b8%ad%e0%b8%99%e0%b8%94%e0%b9%89%e0%b8%b2-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a1%e0%b8%9a%e0%b8%b4\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kpi.co.th\/kpi\/garage\/%e0%b8%aa%e0%b8%b8%e0%b8%a3%e0%b8%b2%e0%b8%a9%e0%b8%8e%e0%b8%a3%e0%b9%8c%e0%b8%ae%e0%b8%ad%e0%b8%99%e0%b8%94%e0%b9%89%e0%b8%b2-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a1%e0%b8%9a%e0%b8%b4\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.kpi.co.th\/kpi\/garage\/%e0%b8%aa%e0%b8%b8%e0%b8%a3%e0%b8%b2%e0%b8%a9%e0%b8%8e%e0%b8%a3%e0%b9%8c%e0%b8%ae%e0%b8%ad%e0%b8%99%e0%b8%94%e0%b9%89%e0%b8%b2-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a1%e0%b8%9a%e0%b8%b4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kpi.co.th\/kpi\/"},{"@type":"ListItem","position":2,"name":"\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32 \u0e2d\u0e2d\u0e42\u0e15\u0e42\u0e21\u0e1a\u0e34\u0e25"}]},{"@type":"WebSite","@id":"https:\/\/www.kpi.co.th\/kpi\/#website","url":"https:\/\/www.kpi.co.th\/kpi\/","name":"KPI","description":"KPI","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kpi.co.th\/kpi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"}]}},"_links":{"self":[{"href":"https:\/\/www.kpi.co.th\/kpi\/wp-json\/wp\/v2\/garage\/13091","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kpi.co.th\/kpi\/wp-json\/wp\/v2\/garage"}],"about":[{"href":"https:\/\/www.kpi.co.th\/kpi\/wp-json\/wp\/v2\/types\/garage"}],"wp:attachment":[{"href":"https:\/\/www.kpi.co.th\/kpi\/wp-json\/wp\/v2\/media?parent=13091"}],"wp:term":[{"taxonomy":"car_type","embeddable":true,"href":"https:\/\/www.kpi.co.th\/kpi\/wp-json\/wp\/v2\/car_type?post=13091"},{"taxonomy":"garage_type","embeddable":true,"href":"https:\/\/www.kpi.co.th\/kpi\/wp-json\/wp\/v2\/garage_type?post=13091"},{"taxonomy":"car_brand","embeddable":true,"href":"https:\/\/www.kpi.co.th\/kpi\/wp-json\/wp\/v2\/car_brand?post=13091"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}