{"id":12614,"date":"2024-03-02T17:37:07","date_gmt":"2024-03-02T10:37:07","guid":{"rendered":"https:\/\/www.kpi.co.th\/kpi\/garage\/%e0%b9%80%e0%b8%97%e0%b9%87%e0%b8%99-%e0%b8%ae%e0%b8%ad%e0%b8%99%e0%b8%94%e0%b9%89%e0%b8%b2-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a1%e0%b8%9a%e0%b8%b4%e0%b8%a5-%e0%b8%9e%e0%b8%a3-2\/"},"modified":"2025-09-11T14:13:28","modified_gmt":"2025-09-11T07:13:28","slug":"%e0%b9%80%e0%b8%97%e0%b9%87%e0%b8%99-%e0%b8%ae%e0%b8%ad%e0%b8%99%e0%b8%94%e0%b9%89%e0%b8%b2-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a1%e0%b8%9a%e0%b8%b4%e0%b8%a5-%e0%b8%9e%e0%b8%a3","status":"publish","type":"garage","link":"https:\/\/www.kpi.co.th\/kpi\/garage\/%e0%b9%80%e0%b8%97%e0%b9%87%e0%b8%99-%e0%b8%ae%e0%b8%ad%e0%b8%99%e0%b8%94%e0%b9%89%e0%b8%b2-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a1%e0%b8%9a%e0%b8%b4%e0%b8%a5-%e0%b8%9e%e0%b8%a3\/","title":{"rendered":"\u0e40\u0e17\u0e47\u0e19 \u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32 \u0e2d\u0e2d\u0e42\u0e15\u0e42\u0e21\u0e1a\u0e34\u0e25 (\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e214)"},"content":{"rendered":"\n<p>4141\/41 \u0e16.\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e214 \u0e41\u0e02\u0e27\u0e07\u0e1e\u0e23\u0e30\u0e42\u0e02\u0e19\u0e07 \u0e40\u0e02\u0e15\u0e04\u0e25\u0e2d\u0e07\u0e40\u0e15\u0e22 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 10110<\/p>\n\n","protected":false},"featured_media":0,"template":"","car_type":[],"garage_type":[261,105],"car_brand":[60],"class_list":["post-12614","garage","type-garage","status-publish","hentry","garage_type-all-garage-servicecenter-autoglass","garage_type-service-center","car_brand-honda"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e40\u0e17\u0e47\u0e19 \u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32 \u0e2d\u0e2d\u0e42\u0e15\u0e42\u0e21\u0e1a\u0e34\u0e25 (\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e214) - KPI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kpi.co.th\/kpi\/garage\/%e0%b9%80%e0%b8%97%e0%b9%87%e0%b8%99-%e0%b8%ae%e0%b8%ad%e0%b8%99%e0%b8%94%e0%b9%89%e0%b8%b2-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a1%e0%b8%9a%e0%b8%b4%e0%b8%a5-%e0%b8%9e%e0%b8%a3\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e40\u0e17\u0e47\u0e19 \u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32 \u0e2d\u0e2d\u0e42\u0e15\u0e42\u0e21\u0e1a\u0e34\u0e25 (\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e214) - KPI\" \/>\n<meta property=\"og:description\" content=\"4141\/41 \u0e16.\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e214 \u0e41\u0e02\u0e27\u0e07\u0e1e\u0e23\u0e30\u0e42\u0e02\u0e19\u0e07 \u0e40\u0e02\u0e15\u0e04\u0e25\u0e2d\u0e07\u0e40\u0e15\u0e22 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kpi.co.th\/kpi\/garage\/%e0%b9%80%e0%b8%97%e0%b9%87%e0%b8%99-%e0%b8%ae%e0%b8%ad%e0%b8%99%e0%b8%94%e0%b9%89%e0%b8%b2-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a1%e0%b8%9a%e0%b8%b4%e0%b8%a5-%e0%b8%9e%e0%b8%a3\/\" \/>\n<meta property=\"og:site_name\" content=\"KPI\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-11T07:13:28+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 \u0e19\u0e32\u0e17\u0e35\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/garage\\\/%e0%b9%80%e0%b8%97%e0%b9%87%e0%b8%99-%e0%b8%ae%e0%b8%ad%e0%b8%99%e0%b8%94%e0%b9%89%e0%b8%b2-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a1%e0%b8%9a%e0%b8%b4%e0%b8%a5-%e0%b8%9e%e0%b8%a3\\\/\",\"url\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/garage\\\/%e0%b9%80%e0%b8%97%e0%b9%87%e0%b8%99-%e0%b8%ae%e0%b8%ad%e0%b8%99%e0%b8%94%e0%b9%89%e0%b8%b2-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a1%e0%b8%9a%e0%b8%b4%e0%b8%a5-%e0%b8%9e%e0%b8%a3\\\/\",\"name\":\"\u0e40\u0e17\u0e47\u0e19 \u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32 \u0e2d\u0e2d\u0e42\u0e15\u0e42\u0e21\u0e1a\u0e34\u0e25 (\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e214) - KPI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/#website\"},\"datePublished\":\"2024-03-02T10:37:07+00:00\",\"dateModified\":\"2025-09-11T07:13:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/garage\\\/%e0%b9%80%e0%b8%97%e0%b9%87%e0%b8%99-%e0%b8%ae%e0%b8%ad%e0%b8%99%e0%b8%94%e0%b9%89%e0%b8%b2-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a1%e0%b8%9a%e0%b8%b4%e0%b8%a5-%e0%b8%9e%e0%b8%a3\\\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/garage\\\/%e0%b9%80%e0%b8%97%e0%b9%87%e0%b8%99-%e0%b8%ae%e0%b8%ad%e0%b8%99%e0%b8%94%e0%b9%89%e0%b8%b2-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a1%e0%b8%9a%e0%b8%b4%e0%b8%a5-%e0%b8%9e%e0%b8%a3\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/garage\\\/%e0%b9%80%e0%b8%97%e0%b9%87%e0%b8%99-%e0%b8%ae%e0%b8%ad%e0%b8%99%e0%b8%94%e0%b9%89%e0%b8%b2-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a1%e0%b8%9a%e0%b8%b4%e0%b8%a5-%e0%b8%9e%e0%b8%a3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e40\u0e17\u0e47\u0e19 \u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32 \u0e2d\u0e2d\u0e42\u0e15\u0e42\u0e21\u0e1a\u0e34\u0e25 (\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e214)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/#website\",\"url\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/\",\"name\":\"KPI\",\"description\":\"KPI\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e40\u0e17\u0e47\u0e19 \u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32 \u0e2d\u0e2d\u0e42\u0e15\u0e42\u0e21\u0e1a\u0e34\u0e25 (\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e214) - KPI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kpi.co.th\/kpi\/garage\/%e0%b9%80%e0%b8%97%e0%b9%87%e0%b8%99-%e0%b8%ae%e0%b8%ad%e0%b8%99%e0%b8%94%e0%b9%89%e0%b8%b2-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a1%e0%b8%9a%e0%b8%b4%e0%b8%a5-%e0%b8%9e%e0%b8%a3\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e40\u0e17\u0e47\u0e19 \u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32 \u0e2d\u0e2d\u0e42\u0e15\u0e42\u0e21\u0e1a\u0e34\u0e25 (\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e214) - KPI","og_description":"4141\/41 \u0e16.\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e214 \u0e41\u0e02\u0e27\u0e07\u0e1e\u0e23\u0e30\u0e42\u0e02\u0e19\u0e07 \u0e40\u0e02\u0e15\u0e04\u0e25\u0e2d\u0e07\u0e40\u0e15\u0e22 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 [&hellip;]","og_url":"https:\/\/www.kpi.co.th\/kpi\/garage\/%e0%b9%80%e0%b8%97%e0%b9%87%e0%b8%99-%e0%b8%ae%e0%b8%ad%e0%b8%99%e0%b8%94%e0%b9%89%e0%b8%b2-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a1%e0%b8%9a%e0%b8%b4%e0%b8%a5-%e0%b8%9e%e0%b8%a3\/","og_site_name":"KPI","article_modified_time":"2025-09-11T07:13:28+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 \u0e19\u0e32\u0e17\u0e35"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.kpi.co.th\/kpi\/garage\/%e0%b9%80%e0%b8%97%e0%b9%87%e0%b8%99-%e0%b8%ae%e0%b8%ad%e0%b8%99%e0%b8%94%e0%b9%89%e0%b8%b2-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a1%e0%b8%9a%e0%b8%b4%e0%b8%a5-%e0%b8%9e%e0%b8%a3\/","url":"https:\/\/www.kpi.co.th\/kpi\/garage\/%e0%b9%80%e0%b8%97%e0%b9%87%e0%b8%99-%e0%b8%ae%e0%b8%ad%e0%b8%99%e0%b8%94%e0%b9%89%e0%b8%b2-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a1%e0%b8%9a%e0%b8%b4%e0%b8%a5-%e0%b8%9e%e0%b8%a3\/","name":"\u0e40\u0e17\u0e47\u0e19 \u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32 \u0e2d\u0e2d\u0e42\u0e15\u0e42\u0e21\u0e1a\u0e34\u0e25 (\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e214) - KPI","isPartOf":{"@id":"https:\/\/www.kpi.co.th\/kpi\/#website"},"datePublished":"2024-03-02T10:37:07+00:00","dateModified":"2025-09-11T07:13:28+00:00","breadcrumb":{"@id":"https:\/\/www.kpi.co.th\/kpi\/garage\/%e0%b9%80%e0%b8%97%e0%b9%87%e0%b8%99-%e0%b8%ae%e0%b8%ad%e0%b8%99%e0%b8%94%e0%b9%89%e0%b8%b2-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a1%e0%b8%9a%e0%b8%b4%e0%b8%a5-%e0%b8%9e%e0%b8%a3\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kpi.co.th\/kpi\/garage\/%e0%b9%80%e0%b8%97%e0%b9%87%e0%b8%99-%e0%b8%ae%e0%b8%ad%e0%b8%99%e0%b8%94%e0%b9%89%e0%b8%b2-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a1%e0%b8%9a%e0%b8%b4%e0%b8%a5-%e0%b8%9e%e0%b8%a3\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.kpi.co.th\/kpi\/garage\/%e0%b9%80%e0%b8%97%e0%b9%87%e0%b8%99-%e0%b8%ae%e0%b8%ad%e0%b8%99%e0%b8%94%e0%b9%89%e0%b8%b2-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a1%e0%b8%9a%e0%b8%b4%e0%b8%a5-%e0%b8%9e%e0%b8%a3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kpi.co.th\/kpi\/"},{"@type":"ListItem","position":2,"name":"\u0e40\u0e17\u0e47\u0e19 \u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32 \u0e2d\u0e2d\u0e42\u0e15\u0e42\u0e21\u0e1a\u0e34\u0e25 (\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e214)"}]},{"@type":"WebSite","@id":"https:\/\/www.kpi.co.th\/kpi\/#website","url":"https:\/\/www.kpi.co.th\/kpi\/","name":"KPI","description":"KPI","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kpi.co.th\/kpi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"}]}},"_links":{"self":[{"href":"https:\/\/www.kpi.co.th\/kpi\/wp-json\/wp\/v2\/garage\/12614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kpi.co.th\/kpi\/wp-json\/wp\/v2\/garage"}],"about":[{"href":"https:\/\/www.kpi.co.th\/kpi\/wp-json\/wp\/v2\/types\/garage"}],"wp:attachment":[{"href":"https:\/\/www.kpi.co.th\/kpi\/wp-json\/wp\/v2\/media?parent=12614"}],"wp:term":[{"taxonomy":"car_type","embeddable":true,"href":"https:\/\/www.kpi.co.th\/kpi\/wp-json\/wp\/v2\/car_type?post=12614"},{"taxonomy":"garage_type","embeddable":true,"href":"https:\/\/www.kpi.co.th\/kpi\/wp-json\/wp\/v2\/garage_type?post=12614"},{"taxonomy":"car_brand","embeddable":true,"href":"https:\/\/www.kpi.co.th\/kpi\/wp-json\/wp\/v2\/car_brand?post=12614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}