{"id":13490,"date":"2024-01-16T16:26:29","date_gmt":"2024-01-16T09:26:29","guid":{"rendered":"https:\/\/www.kpi.co.th\/kpi\/news\/news6\/"},"modified":"2024-01-16T16:26:29","modified_gmt":"2024-01-16T09:26:29","slug":"news6","status":"publish","type":"news","link":"https:\/\/www.kpi.co.th\/kpi\/en\/news\/news6\/","title":{"rendered":"\u0e01\u0e23\u0e38\u0e07\u0e44\u0e17\u0e22\u0e1e\u0e32\u0e19\u0e34\u0e0a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22\u0e40\u0e02\u0e49\u0e32\u0e23\u0e31\u0e1a\u0e21\u0e2d\u0e1a\u0e40\u0e02\u0e47\u0e21\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e04\u0e38\u0e13\u0e0a\u0e21\u0e23\u0e21\u0e08\u0e23\u0e23\u0e22\u0e32\u0e1a\u0e23\u0e23\u0e13\u0e2b\u0e2d\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e44\u0e17\u0e22 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2565 \u0e01\u0e32\u0e23\u0e31\u0e19\u0e15\u0e35\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e08\u0e23\u0e23\u0e22\u0e32\u0e1a\u0e23\u0e23\u0e13 \u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e1b\u0e35\u0e17\u0e35\u0e48 70"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"671\" src=\"https:\/\/www.kpi.co.th\/wp-content\/uploads\/2024\/01\/006-1024x671.jpg\" alt=\"006\" class=\"wp-image-876\" srcset=\"https:\/\/www.kpi.co.th\/wp-content\/uploads\/2024\/01\/006-1024x671.jpg 1024w, https:\/\/www.kpi.co.th\/wp-content\/uploads\/2024\/01\/006-300x196.jpg 300w, https:\/\/www.kpi.co.th\/wp-content\/uploads\/2024\/01\/006-768x503.jpg 768w, https:\/\/www.kpi.co.th\/wp-content\/uploads\/2024\/01\/006.jpg 1440w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e44\u0e17\u0e22\u0e1e\u0e32\u0e19\u0e34\u0e0a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19) \u0e2b\u0e23\u0e37\u0e2d \u0e40\u0e04\u0e1e\u0e35\u0e44\u0e2d \u0e40\u0e02\u0e49\u0e32\u0e23\u0e31\u0e1a\u0e21\u0e2d\u0e1a\u0e40\u0e02\u0e47\u0e21\u0e01\u0e25\u0e31\u0e14\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e04\u0e38\u0e13\u0e0a\u0e21\u0e23\u0e21\u0e08\u0e23\u0e23\u0e22\u0e32\u0e1a\u0e23\u0e23\u0e13\u0e2b\u0e2d\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e44\u0e17\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e15\u0e2d\u0e01\u0e22\u0e49\u0e33\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e08\u0e23\u0e23\u0e22\u0e32\u0e1a\u0e23\u0e23\u0e13\u0e14\u0e35\u0e40\u0e14\u0e48\u0e19 \u0e08\u0e32\u0e01\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e04\u0e38\u0e13\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e08\u0e32\u0e01\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e2b\u0e2d\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e44\u0e17\u0e22 \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e2d\u0e1a\u0e42\u0e14\u0e22\u0e04\u0e38\u0e13\u0e2a\u0e19\u0e31\u0e48\u0e19 \u0e2d\u0e31\u0e07\u0e2d\u0e38\u0e1a\u0e25\u0e01\u0e38\u0e25 \u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e2b\u0e2d\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e44\u0e17\u0e22 \u0e41\u0e25\u0e30\u0e04\u0e38\u0e13\u0e27\u0e35\u0e19\u0e31\u0e2a \u0e2d\u0e31\u0e28\u0e27\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e16\u0e32\u0e27\u0e23 \u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e15\u0e48\u0e2d\u0e15\u0e49\u0e32\u0e19\u0e04\u0e2d\u0e23\u0e4c\u0e23\u0e31\u0e1b\u0e0a\u0e31\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e08\u0e23\u0e23\u0e22\u0e32\u0e1a\u0e23\u0e23\u0e13 \u0e2b\u0e2d\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e44\u0e17\u0e22 \u0e13 \u0e2b\u0e49\u0e2d\u0e07 UTCC EVENTS LAB \u0e2d\u0e32\u0e04\u0e32\u0e23 23 \u0e0a\u0e31\u0e49\u0e19 7 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2b\u0e2d\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e44\u0e17\u0e22<\/p>\n\n\n\n<p><br>\u0e40\u0e02\u0e47\u0e21\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e04\u0e38\u0e13\u0e2f \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e37\u0e19\u0e22\u0e31\u0e19\u0e16\u0e36\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2f \u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e14\u0e49\u0e27\u0e22\u0e22\u0e36\u0e14\u0e2b\u0e25\u0e31\u0e01\u0e08\u0e23\u0e23\u0e22\u0e32\u0e1a\u0e23\u0e23\u0e13\u0e41\u0e25\u0e30\u0e2b\u0e25\u0e31\u0e01\u0e1a\u0e23\u0e23\u0e29\u0e31\u0e17\u0e20\u0e34\u0e1a\u0e32\u0e25 (Good Corporate Governance) \u0e43\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e0b\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e15\u0e22\u0e4c\u0e2a\u0e38\u0e08\u0e23\u0e34\u0e15 \u0e42\u0e1b\u0e23\u0e48\u0e07\u0e43\u0e2a \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e44\u0e14\u0e49 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 \u0e08\u0e36\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e37\u0e19\u0e22\u0e31\u0e19\u0e44\u0e14\u0e49\u0e27\u0e48\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e44\u0e17\u0e22\u0e1e\u0e32\u0e19\u0e34\u0e0a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22 \u0e01\u0e33\u0e25\u0e31\u0e07\u0e08\u0e30\u0e01\u0e49\u0e32\u0e27\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e1b\u0e35\u0e17\u0e35\u0e48 70 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e2d\u0e31\u0e19\u0e21\u0e35\u0e40\u0e02\u0e47\u0e21\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e04\u0e38\u0e13\u0e0a\u0e21\u0e23\u0e21\u0e08\u0e23\u0e23\u0e22\u0e32\u0e1a\u0e23\u0e23\u0e13\u0e2b\u0e2d\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e44\u0e17<\/p>\n","protected":false},"featured_media":877,"template":"","blog_featured":[],"class_list":["post-13490","news","type-news","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e01\u0e23\u0e38\u0e07\u0e44\u0e17\u0e22\u0e1e\u0e32\u0e19\u0e34\u0e0a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22\u0e40\u0e02\u0e49\u0e32\u0e23\u0e31\u0e1a\u0e21\u0e2d\u0e1a\u0e40\u0e02\u0e47\u0e21\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e04\u0e38\u0e13\u0e0a\u0e21\u0e23\u0e21\u0e08\u0e23\u0e23\u0e22\u0e32\u0e1a\u0e23\u0e23\u0e13\u0e2b\u0e2d\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e44\u0e17\u0e22 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2565 \u0e01\u0e32\u0e23\u0e31\u0e19\u0e15\u0e35\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e08\u0e23\u0e23\u0e22\u0e32\u0e1a\u0e23\u0e23\u0e13 \u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e1b\u0e35\u0e17\u0e35\u0e48 70 - KPI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kpi.co.th\/kpi\/en\/news\/news6\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e01\u0e23\u0e38\u0e07\u0e44\u0e17\u0e22\u0e1e\u0e32\u0e19\u0e34\u0e0a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22\u0e40\u0e02\u0e49\u0e32\u0e23\u0e31\u0e1a\u0e21\u0e2d\u0e1a\u0e40\u0e02\u0e47\u0e21\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e04\u0e38\u0e13\u0e0a\u0e21\u0e23\u0e21\u0e08\u0e23\u0e23\u0e22\u0e32\u0e1a\u0e23\u0e23\u0e13\u0e2b\u0e2d\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e44\u0e17\u0e22 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2565 \u0e01\u0e32\u0e23\u0e31\u0e19\u0e15\u0e35\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e08\u0e23\u0e23\u0e22\u0e32\u0e1a\u0e23\u0e23\u0e13 \u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e1b\u0e35\u0e17\u0e35\u0e48 70 - KPI\" \/>\n<meta property=\"og:description\" content=\"\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e44\u0e17\u0e22\u0e1e\u0e32\u0e19\u0e34\u0e0a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19) \u0e2b\u0e23\u0e37\u0e2d \u0e40\u0e04\u0e1e\u0e35\u0e44\u0e2d \u0e40\u0e02\u0e49\u0e32\u0e23\u0e31\u0e1a\u0e21\u0e2d\u0e1a\u0e40\u0e02\u0e47\u0e21\u0e01\u0e25\u0e31\u0e14\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e04\u0e38\u0e13\u0e0a\u0e21\u0e23\u0e21\u0e08\u0e23\u0e23\u0e22\u0e32\u0e1a\u0e23\u0e23\u0e13\u0e2b\u0e2d\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e44\u0e17\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e15\u0e2d\u0e01\u0e22\u0e49\u0e33\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e08\u0e23\u0e23\u0e22\u0e32\u0e1a\u0e23\u0e23\u0e13\u0e14\u0e35\u0e40\u0e14\u0e48\u0e19 \u0e08\u0e32\u0e01\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e04\u0e38\u0e13\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e08\u0e32\u0e01\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e2b\u0e2d\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e44\u0e17\u0e22 \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e2d\u0e1a\u0e42\u0e14\u0e22\u0e04\u0e38\u0e13\u0e2a\u0e19\u0e31\u0e48\u0e19 \u0e2d\u0e31\u0e07\u0e2d\u0e38\u0e1a\u0e25\u0e01\u0e38\u0e25 \u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e2b\u0e2d\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e44\u0e17\u0e22 \u0e41\u0e25\u0e30\u0e04\u0e38\u0e13\u0e27\u0e35\u0e19\u0e31\u0e2a \u0e2d\u0e31\u0e28\u0e27\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e16\u0e32\u0e27\u0e23 \u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e15\u0e48\u0e2d\u0e15\u0e49\u0e32\u0e19\u0e04\u0e2d\u0e23\u0e4c\u0e23\u0e31\u0e1b\u0e0a\u0e31\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e08\u0e23\u0e23\u0e22\u0e32\u0e1a\u0e23\u0e23\u0e13 \u0e2b\u0e2d\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e44\u0e17\u0e22 \u0e13 \u0e2b\u0e49\u0e2d\u0e07 UTCC EVENTS LAB \u0e2d\u0e32\u0e04\u0e32\u0e23 23 \u0e0a\u0e31\u0e49\u0e19 7 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2b\u0e2d\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e44\u0e17\u0e22 \u0e40\u0e02\u0e47\u0e21\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e04\u0e38\u0e13\u0e2f \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e37\u0e19\u0e22\u0e31\u0e19\u0e16\u0e36\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2f \u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e14\u0e49\u0e27\u0e22\u0e22\u0e36\u0e14\u0e2b\u0e25\u0e31\u0e01\u0e08\u0e23\u0e23\u0e22\u0e32\u0e1a\u0e23\u0e23\u0e13\u0e41\u0e25\u0e30\u0e2b\u0e25\u0e31\u0e01\u0e1a\u0e23\u0e23\u0e29\u0e31\u0e17\u0e20\u0e34\u0e1a\u0e32\u0e25 (Good Corporate Governance) \u0e43\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e0b\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e15\u0e22\u0e4c\u0e2a\u0e38\u0e08\u0e23\u0e34\u0e15 \u0e42\u0e1b\u0e23\u0e48\u0e07\u0e43\u0e2a \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e44\u0e14\u0e49 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 \u0e08\u0e36\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e37\u0e19\u0e22\u0e31\u0e19\u0e44\u0e14\u0e49\u0e27\u0e48\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e44\u0e17\u0e22\u0e1e\u0e32\u0e19\u0e34\u0e0a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22 \u0e01\u0e33\u0e25\u0e31\u0e07\u0e08\u0e30\u0e01\u0e49\u0e32\u0e27\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e1b\u0e35\u0e17\u0e35\u0e48 70 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e2d\u0e31\u0e19\u0e21\u0e35\u0e40\u0e02\u0e47\u0e21\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e04\u0e38\u0e13\u0e0a\u0e21\u0e23\u0e21\u0e08\u0e23\u0e23\u0e22\u0e32\u0e1a\u0e23\u0e23\u0e13\u0e2b\u0e2d\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e44\u0e17\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kpi.co.th\/kpi\/en\/news\/news6\/\" \/>\n<meta property=\"og:site_name\" content=\"KPI\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kpi.co.th\/wp-content\/uploads\/2024\/01\/006-1024x671.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/en\\\/news\\\/news6\\\/\",\"url\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/en\\\/news\\\/news6\\\/\",\"name\":\"\u0e01\u0e23\u0e38\u0e07\u0e44\u0e17\u0e22\u0e1e\u0e32\u0e19\u0e34\u0e0a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22\u0e40\u0e02\u0e49\u0e32\u0e23\u0e31\u0e1a\u0e21\u0e2d\u0e1a\u0e40\u0e02\u0e47\u0e21\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e04\u0e38\u0e13\u0e0a\u0e21\u0e23\u0e21\u0e08\u0e23\u0e23\u0e22\u0e32\u0e1a\u0e23\u0e23\u0e13\u0e2b\u0e2d\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e44\u0e17\u0e22 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2565 \u0e01\u0e32\u0e23\u0e31\u0e19\u0e15\u0e35\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e08\u0e23\u0e23\u0e22\u0e32\u0e1a\u0e23\u0e23\u0e13 \u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e1b\u0e35\u0e17\u0e35\u0e48 70 - KPI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/en\\\/news\\\/news6\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/en\\\/news\\\/news6\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kpi.co.th\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/006.jpg\",\"datePublished\":\"2024-01-16T09:26:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/en\\\/news\\\/news6\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/en\\\/news\\\/news6\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/en\\\/news\\\/news6\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kpi.co.th\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/006.jpg\",\"contentUrl\":\"https:\\\/\\\/www.kpi.co.th\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/006.jpg\",\"width\":1440,\"height\":943},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/en\\\/news\\\/news6\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/en\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0e01\u0e23\u0e38\u0e07\u0e44\u0e17\u0e22\u0e1e\u0e32\u0e19\u0e34\u0e0a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22\u0e40\u0e02\u0e49\u0e32\u0e23\u0e31\u0e1a\u0e21\u0e2d\u0e1a\u0e40\u0e02\u0e47\u0e21\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e04\u0e38\u0e13\u0e0a\u0e21\u0e23\u0e21\u0e08\u0e23\u0e23\u0e22\u0e32\u0e1a\u0e23\u0e23\u0e13\u0e2b\u0e2d\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e44\u0e17\u0e22 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2565 \u0e01\u0e32\u0e23\u0e31\u0e19\u0e15\u0e35\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e08\u0e23\u0e23\u0e22\u0e32\u0e1a\u0e23\u0e23\u0e13 \u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e1b\u0e35\u0e17\u0e35\u0e48 70\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/en\\\/\",\"name\":\"KPI\",\"description\":\"KPI\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e01\u0e23\u0e38\u0e07\u0e44\u0e17\u0e22\u0e1e\u0e32\u0e19\u0e34\u0e0a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22\u0e40\u0e02\u0e49\u0e32\u0e23\u0e31\u0e1a\u0e21\u0e2d\u0e1a\u0e40\u0e02\u0e47\u0e21\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e04\u0e38\u0e13\u0e0a\u0e21\u0e23\u0e21\u0e08\u0e23\u0e23\u0e22\u0e32\u0e1a\u0e23\u0e23\u0e13\u0e2b\u0e2d\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e44\u0e17\u0e22 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2565 \u0e01\u0e32\u0e23\u0e31\u0e19\u0e15\u0e35\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e08\u0e23\u0e23\u0e22\u0e32\u0e1a\u0e23\u0e23\u0e13 \u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e1b\u0e35\u0e17\u0e35\u0e48 70 - KPI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kpi.co.th\/kpi\/en\/news\/news6\/","og_locale":"en_US","og_type":"article","og_title":"\u0e01\u0e23\u0e38\u0e07\u0e44\u0e17\u0e22\u0e1e\u0e32\u0e19\u0e34\u0e0a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22\u0e40\u0e02\u0e49\u0e32\u0e23\u0e31\u0e1a\u0e21\u0e2d\u0e1a\u0e40\u0e02\u0e47\u0e21\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e04\u0e38\u0e13\u0e0a\u0e21\u0e23\u0e21\u0e08\u0e23\u0e23\u0e22\u0e32\u0e1a\u0e23\u0e23\u0e13\u0e2b\u0e2d\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e44\u0e17\u0e22 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2565 \u0e01\u0e32\u0e23\u0e31\u0e19\u0e15\u0e35\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e08\u0e23\u0e23\u0e22\u0e32\u0e1a\u0e23\u0e23\u0e13 \u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e1b\u0e35\u0e17\u0e35\u0e48 70 - KPI","og_description":"\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e44\u0e17\u0e22\u0e1e\u0e32\u0e19\u0e34\u0e0a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19) \u0e2b\u0e23\u0e37\u0e2d \u0e40\u0e04\u0e1e\u0e35\u0e44\u0e2d \u0e40\u0e02\u0e49\u0e32\u0e23\u0e31\u0e1a\u0e21\u0e2d\u0e1a\u0e40\u0e02\u0e47\u0e21\u0e01\u0e25\u0e31\u0e14\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e04\u0e38\u0e13\u0e0a\u0e21\u0e23\u0e21\u0e08\u0e23\u0e23\u0e22\u0e32\u0e1a\u0e23\u0e23\u0e13\u0e2b\u0e2d\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e44\u0e17\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e15\u0e2d\u0e01\u0e22\u0e49\u0e33\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e08\u0e23\u0e23\u0e22\u0e32\u0e1a\u0e23\u0e23\u0e13\u0e14\u0e35\u0e40\u0e14\u0e48\u0e19 \u0e08\u0e32\u0e01\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e04\u0e38\u0e13\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e08\u0e32\u0e01\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e2b\u0e2d\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e44\u0e17\u0e22 \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e2d\u0e1a\u0e42\u0e14\u0e22\u0e04\u0e38\u0e13\u0e2a\u0e19\u0e31\u0e48\u0e19 \u0e2d\u0e31\u0e07\u0e2d\u0e38\u0e1a\u0e25\u0e01\u0e38\u0e25 \u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e2b\u0e2d\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e44\u0e17\u0e22 \u0e41\u0e25\u0e30\u0e04\u0e38\u0e13\u0e27\u0e35\u0e19\u0e31\u0e2a \u0e2d\u0e31\u0e28\u0e27\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e16\u0e32\u0e27\u0e23 \u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e15\u0e48\u0e2d\u0e15\u0e49\u0e32\u0e19\u0e04\u0e2d\u0e23\u0e4c\u0e23\u0e31\u0e1b\u0e0a\u0e31\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e08\u0e23\u0e23\u0e22\u0e32\u0e1a\u0e23\u0e23\u0e13 \u0e2b\u0e2d\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e44\u0e17\u0e22 \u0e13 \u0e2b\u0e49\u0e2d\u0e07 UTCC EVENTS LAB \u0e2d\u0e32\u0e04\u0e32\u0e23 23 \u0e0a\u0e31\u0e49\u0e19 7 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2b\u0e2d\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e44\u0e17\u0e22 \u0e40\u0e02\u0e47\u0e21\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e04\u0e38\u0e13\u0e2f \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e37\u0e19\u0e22\u0e31\u0e19\u0e16\u0e36\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2f \u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e14\u0e49\u0e27\u0e22\u0e22\u0e36\u0e14\u0e2b\u0e25\u0e31\u0e01\u0e08\u0e23\u0e23\u0e22\u0e32\u0e1a\u0e23\u0e23\u0e13\u0e41\u0e25\u0e30\u0e2b\u0e25\u0e31\u0e01\u0e1a\u0e23\u0e23\u0e29\u0e31\u0e17\u0e20\u0e34\u0e1a\u0e32\u0e25 (Good Corporate Governance) \u0e43\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e0b\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e15\u0e22\u0e4c\u0e2a\u0e38\u0e08\u0e23\u0e34\u0e15 \u0e42\u0e1b\u0e23\u0e48\u0e07\u0e43\u0e2a \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e44\u0e14\u0e49 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 \u0e08\u0e36\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e37\u0e19\u0e22\u0e31\u0e19\u0e44\u0e14\u0e49\u0e27\u0e48\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e44\u0e17\u0e22\u0e1e\u0e32\u0e19\u0e34\u0e0a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22 \u0e01\u0e33\u0e25\u0e31\u0e07\u0e08\u0e30\u0e01\u0e49\u0e32\u0e27\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e1b\u0e35\u0e17\u0e35\u0e48 70 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e2d\u0e31\u0e19\u0e21\u0e35\u0e40\u0e02\u0e47\u0e21\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e04\u0e38\u0e13\u0e0a\u0e21\u0e23\u0e21\u0e08\u0e23\u0e23\u0e22\u0e32\u0e1a\u0e23\u0e23\u0e13\u0e2b\u0e2d\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e44\u0e17","og_url":"https:\/\/www.kpi.co.th\/kpi\/en\/news\/news6\/","og_site_name":"KPI","og_image":[{"url":"https:\/\/www.kpi.co.th\/wp-content\/uploads\/2024\/01\/006-1024x671.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.kpi.co.th\/kpi\/en\/news\/news6\/","url":"https:\/\/www.kpi.co.th\/kpi\/en\/news\/news6\/","name":"\u0e01\u0e23\u0e38\u0e07\u0e44\u0e17\u0e22\u0e1e\u0e32\u0e19\u0e34\u0e0a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22\u0e40\u0e02\u0e49\u0e32\u0e23\u0e31\u0e1a\u0e21\u0e2d\u0e1a\u0e40\u0e02\u0e47\u0e21\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e04\u0e38\u0e13\u0e0a\u0e21\u0e23\u0e21\u0e08\u0e23\u0e23\u0e22\u0e32\u0e1a\u0e23\u0e23\u0e13\u0e2b\u0e2d\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e44\u0e17\u0e22 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2565 \u0e01\u0e32\u0e23\u0e31\u0e19\u0e15\u0e35\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e08\u0e23\u0e23\u0e22\u0e32\u0e1a\u0e23\u0e23\u0e13 \u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e1b\u0e35\u0e17\u0e35\u0e48 70 - KPI","isPartOf":{"@id":"https:\/\/www.kpi.co.th\/kpi\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kpi.co.th\/kpi\/en\/news\/news6\/#primaryimage"},"image":{"@id":"https:\/\/www.kpi.co.th\/kpi\/en\/news\/news6\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kpi.co.th\/wp-content\/uploads\/2024\/01\/006.jpg","datePublished":"2024-01-16T09:26:29+00:00","breadcrumb":{"@id":"https:\/\/www.kpi.co.th\/kpi\/en\/news\/news6\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kpi.co.th\/kpi\/en\/news\/news6\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.kpi.co.th\/kpi\/en\/news\/news6\/#primaryimage","url":"https:\/\/www.kpi.co.th\/wp-content\/uploads\/2024\/01\/006.jpg","contentUrl":"https:\/\/www.kpi.co.th\/wp-content\/uploads\/2024\/01\/006.jpg","width":1440,"height":943},{"@type":"BreadcrumbList","@id":"https:\/\/www.kpi.co.th\/kpi\/en\/news\/news6\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kpi.co.th\/kpi\/en\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/www.kpi.co.th\/kpi\/en\/news\/"},{"@type":"ListItem","position":3,"name":"\u0e01\u0e23\u0e38\u0e07\u0e44\u0e17\u0e22\u0e1e\u0e32\u0e19\u0e34\u0e0a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22\u0e40\u0e02\u0e49\u0e32\u0e23\u0e31\u0e1a\u0e21\u0e2d\u0e1a\u0e40\u0e02\u0e47\u0e21\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e04\u0e38\u0e13\u0e0a\u0e21\u0e23\u0e21\u0e08\u0e23\u0e23\u0e22\u0e32\u0e1a\u0e23\u0e23\u0e13\u0e2b\u0e2d\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e44\u0e17\u0e22 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2565 \u0e01\u0e32\u0e23\u0e31\u0e19\u0e15\u0e35\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e08\u0e23\u0e23\u0e22\u0e32\u0e1a\u0e23\u0e23\u0e13 \u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e1b\u0e35\u0e17\u0e35\u0e48 70"}]},{"@type":"WebSite","@id":"https:\/\/www.kpi.co.th\/kpi\/en\/#website","url":"https:\/\/www.kpi.co.th\/kpi\/en\/","name":"KPI","description":"KPI","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kpi.co.th\/kpi\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.kpi.co.th\/kpi\/en\/wp-json\/wp\/v2\/news\/13490","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kpi.co.th\/kpi\/en\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/www.kpi.co.th\/kpi\/en\/wp-json\/wp\/v2\/types\/news"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kpi.co.th\/kpi\/en\/wp-json\/wp\/v2\/media\/877"}],"wp:attachment":[{"href":"https:\/\/www.kpi.co.th\/kpi\/en\/wp-json\/wp\/v2\/media?parent=13490"}],"wp:term":[{"taxonomy":"blog_featured","embeddable":true,"href":"https:\/\/www.kpi.co.th\/kpi\/en\/wp-json\/wp\/v2\/blog_featured?post=13490"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}