{"id":13485,"date":"2024-01-16T16:34:02","date_gmt":"2024-01-16T09:34:02","guid":{"rendered":"https:\/\/www.kpi.co.th\/kpi\/news\/news1\/"},"modified":"2024-08-16T14:25:41","modified_gmt":"2024-08-16T07:25:41","slug":"news1","status":"publish","type":"news","link":"https:\/\/www.kpi.co.th\/kpi\/en\/news\/news1\/","title":{"rendered":"\u0e04\u0e23\u0e1a\u0e23\u0e2d\u0e1a 10 \u0e1b\u0e35 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e2b\u0e49\u0e2d\u0e07\u0e2a\u0e21\u0e38\u0e14\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e04\u0e1e\u0e35\u0e44\u0e2d\u201d \u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e2b\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e14\u0e47\u0e01\u0e44\u0e17\u0e22\u0e43\u0e2b\u0e49\u0e17\u0e38\u0e19\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e25\u0e2d\u0e14 10 \u0e1b\u0e35 12 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"671\" src=\"https:\/\/www.kpi.co.th\/wp-content\/uploads\/2024\/01\/001-1024x671.jpg\" alt=\"001\" class=\"wp-image-811\" srcset=\"https:\/\/www.kpi.co.th\/wp-content\/uploads\/2024\/01\/001-1024x671.jpg 1024w, https:\/\/www.kpi.co.th\/wp-content\/uploads\/2024\/01\/001-300x196.jpg 300w, https:\/\/www.kpi.co.th\/wp-content\/uploads\/2024\/01\/001-768x503.jpg 768w, https:\/\/www.kpi.co.th\/wp-content\/uploads\/2024\/01\/001.jpg 1440w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e04\u0e23\u0e1a\u0e23\u0e2d\u0e1a 10 \u0e1b\u0e35 \u0e2b\u0e49\u0e2d\u0e07\u0e2a\u0e21\u0e38\u0e14\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e04\u0e1e\u0e35\u0e44\u0e2d \u0e41\u0e25\u0e30\u0e1e\u0e34\u0e18\u0e35\u0e21\u0e2d\u0e1a\u0e2b\u0e49\u0e2d\u0e07\u0e2a\u0e21\u0e38\u0e14\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e04\u0e1e\u0e35\u0e44\u0e2d \u0e01\u0e49\u0e32\u0e27\u0e17\u0e35\u0e48\u0e1e\u0e23\u0e49\u0e2d\u0e21 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e40\u0e14\u0e47\u0e01\u0e44\u0e17\u0e22 \u0e41\u0e2b\u0e48\u0e07\u0e17\u0e35\u0e48 12 \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d \u0e08. \u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19<br>\u0e04\u0e38\u0e13\u0e2a\u0e38\u0e0a\u0e32\u0e27\u0e14\u0e35 \u0e41\u0e2a\u0e07\u0e2d\u0e19\u0e07\u0e04\u0e4c \u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e0d\u0e48 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e44\u0e17\u0e22\u0e1e\u0e32\u0e19\u0e34\u0e0a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19) \u0e44\u0e14\u0e49\u0e19\u0e33\u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e08\u0e34\u0e15\u0e2d\u0e32\u0e2a\u0e32 \u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e21\u0e32\u0e17\u0e33\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e21\u0e2d\u0e1a\u0e17\u0e38\u0e19\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2b\u0e49\u0e2d\u0e07\u0e2a\u0e21\u0e38\u0e14\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e17\u0e31\u0e49\u0e07 10 \u0e41\u0e2b\u0e48\u0e07 \u0e17\u0e35\u0e48\u0e40\u0e04\u0e22\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2b\u0e49\u0e2d\u0e07\u0e2a\u0e21\u0e38\u0e14\u0e21\u0e32\u0e41\u0e25\u0e49\u0e27 \u0e40\u0e1b\u0e47\u0e19\u0e17\u0e38\u0e19\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e49\u0e19 345,000 \u0e1a\u0e32\u0e17 \u0e41\u0e25\u0e30\u0e21\u0e2d\u0e1a\u0e17\u0e38\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e2d\u0e35\u0e01\u0e08\u0e33\u0e19\u0e27\u0e19 50 \u0e17\u0e38\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e07\u0e34\u0e19 150,000 \u0e1a\u0e32\u0e17<br>\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e19\u0e19\u0e35\u0e49\u0e44\u0e14\u0e49\u0e21\u0e2d\u0e1a\u0e2b\u0e49\u0e2d\u0e07\u0e2a\u0e21\u0e38\u0e14\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e40\u0e04\u0e1e\u0e35\u0e44\u0e2d \u0e41\u0e2b\u0e48\u0e07\u0e17\u0e35\u0e48 12 \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d \u0e08. \u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e17\u0e38\u0e19\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e49\u0e19 450,000 \u0e1a\u0e32\u0e17 \u0e41\u0e25\u0e30\u0e17\u0e38\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2d\u0e35\u0e01\u0e08\u0e33\u0e19\u0e27\u0e19 54 \u0e17\u0e38\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e07\u0e34\u0e19 162,000 \u0e1a\u0e32\u0e17 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 30 \u0e1e\u0e24\u0e28\u0e08\u0e34\u0e01\u0e32\u0e22\u0e19 2566<\/p>\n","protected":false},"featured_media":812,"template":"","blog_featured":[],"class_list":["post-13485","news","type-news","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e04\u0e23\u0e1a\u0e23\u0e2d\u0e1a 10 \u0e1b\u0e35 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e2b\u0e49\u0e2d\u0e07\u0e2a\u0e21\u0e38\u0e14\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e04\u0e1e\u0e35\u0e44\u0e2d\u201d \u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e2b\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e14\u0e47\u0e01\u0e44\u0e17\u0e22\u0e43\u0e2b\u0e49\u0e17\u0e38\u0e19\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e25\u0e2d\u0e14 10 \u0e1b\u0e35 12 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19 - KPI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kpi.co.th\/kpi\/en\/news\/news1\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e04\u0e23\u0e1a\u0e23\u0e2d\u0e1a 10 \u0e1b\u0e35 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e2b\u0e49\u0e2d\u0e07\u0e2a\u0e21\u0e38\u0e14\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e04\u0e1e\u0e35\u0e44\u0e2d\u201d \u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e2b\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e14\u0e47\u0e01\u0e44\u0e17\u0e22\u0e43\u0e2b\u0e49\u0e17\u0e38\u0e19\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e25\u0e2d\u0e14 10 \u0e1b\u0e35 12 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19 - KPI\" \/>\n<meta property=\"og:description\" content=\"\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e04\u0e23\u0e1a\u0e23\u0e2d\u0e1a 10 \u0e1b\u0e35 \u0e2b\u0e49\u0e2d\u0e07\u0e2a\u0e21\u0e38\u0e14\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e04\u0e1e\u0e35\u0e44\u0e2d \u0e41\u0e25\u0e30\u0e1e\u0e34\u0e18\u0e35\u0e21\u0e2d\u0e1a\u0e2b\u0e49\u0e2d\u0e07\u0e2a\u0e21\u0e38\u0e14\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e04\u0e1e\u0e35\u0e44\u0e2d \u0e01\u0e49\u0e32\u0e27\u0e17\u0e35\u0e48\u0e1e\u0e23\u0e49\u0e2d\u0e21 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e40\u0e14\u0e47\u0e01\u0e44\u0e17\u0e22 \u0e41\u0e2b\u0e48\u0e07\u0e17\u0e35\u0e48 12 \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d \u0e08. \u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\u0e04\u0e38\u0e13\u0e2a\u0e38\u0e0a\u0e32\u0e27\u0e14\u0e35 \u0e41\u0e2a\u0e07\u0e2d\u0e19\u0e07\u0e04\u0e4c \u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e0d\u0e48 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e44\u0e17\u0e22\u0e1e\u0e32\u0e19\u0e34\u0e0a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19) \u0e44\u0e14\u0e49\u0e19\u0e33\u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e08\u0e34\u0e15\u0e2d\u0e32\u0e2a\u0e32 \u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e21\u0e32\u0e17\u0e33\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e21\u0e2d\u0e1a\u0e17\u0e38\u0e19\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2b\u0e49\u0e2d\u0e07\u0e2a\u0e21\u0e38\u0e14\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e17\u0e31\u0e49\u0e07 10 \u0e41\u0e2b\u0e48\u0e07 \u0e17\u0e35\u0e48\u0e40\u0e04\u0e22\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2b\u0e49\u0e2d\u0e07\u0e2a\u0e21\u0e38\u0e14\u0e21\u0e32\u0e41\u0e25\u0e49\u0e27 \u0e40\u0e1b\u0e47\u0e19\u0e17\u0e38\u0e19\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e49\u0e19 345,000 \u0e1a\u0e32\u0e17 \u0e41\u0e25\u0e30\u0e21\u0e2d\u0e1a\u0e17\u0e38\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e2d\u0e35\u0e01\u0e08\u0e33\u0e19\u0e27\u0e19 50 \u0e17\u0e38\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e07\u0e34\u0e19 150,000 \u0e1a\u0e32\u0e17\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e19\u0e19\u0e35\u0e49\u0e44\u0e14\u0e49\u0e21\u0e2d\u0e1a\u0e2b\u0e49\u0e2d\u0e07\u0e2a\u0e21\u0e38\u0e14\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e40\u0e04\u0e1e\u0e35\u0e44\u0e2d \u0e41\u0e2b\u0e48\u0e07\u0e17\u0e35\u0e48 12 \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d \u0e08. \u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e17\u0e38\u0e19\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e49\u0e19 450,000 \u0e1a\u0e32\u0e17 \u0e41\u0e25\u0e30\u0e17\u0e38\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2d\u0e35\u0e01\u0e08\u0e33\u0e19\u0e27\u0e19 54 \u0e17\u0e38\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e07\u0e34\u0e19 162,000 \u0e1a\u0e32\u0e17 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 30 \u0e1e\u0e24\u0e28\u0e08\u0e34\u0e01\u0e32\u0e22\u0e19 2566\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kpi.co.th\/kpi\/en\/news\/news1\/\" \/>\n<meta property=\"og:site_name\" content=\"KPI\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-16T07:25:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kpi.co.th\/wp-content\/uploads\/2024\/01\/001.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"943\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/en\\\/news\\\/news1\\\/\",\"url\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/en\\\/news\\\/news1\\\/\",\"name\":\"\u0e04\u0e23\u0e1a\u0e23\u0e2d\u0e1a 10 \u0e1b\u0e35 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e2b\u0e49\u0e2d\u0e07\u0e2a\u0e21\u0e38\u0e14\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e04\u0e1e\u0e35\u0e44\u0e2d\u201d \u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e2b\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e14\u0e47\u0e01\u0e44\u0e17\u0e22\u0e43\u0e2b\u0e49\u0e17\u0e38\u0e19\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e25\u0e2d\u0e14 10 \u0e1b\u0e35 12 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19 - KPI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/en\\\/news\\\/news1\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/en\\\/news\\\/news1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kpi.co.th\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/001.jpg\",\"datePublished\":\"2024-01-16T09:34:02+00:00\",\"dateModified\":\"2024-08-16T07:25:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/en\\\/news\\\/news1\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/en\\\/news\\\/news1\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/en\\\/news\\\/news1\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kpi.co.th\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/001.jpg\",\"contentUrl\":\"https:\\\/\\\/www.kpi.co.th\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/001.jpg\",\"width\":1440,\"height\":943},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/en\\\/news\\\/news1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/en\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0e04\u0e23\u0e1a\u0e23\u0e2d\u0e1a 10 \u0e1b\u0e35 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e2b\u0e49\u0e2d\u0e07\u0e2a\u0e21\u0e38\u0e14\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e04\u0e1e\u0e35\u0e44\u0e2d\u201d \u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e2b\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e14\u0e47\u0e01\u0e44\u0e17\u0e22\u0e43\u0e2b\u0e49\u0e17\u0e38\u0e19\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e25\u0e2d\u0e14 10 \u0e1b\u0e35 12 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/en\\\/\",\"name\":\"KPI\",\"description\":\"KPI\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e04\u0e23\u0e1a\u0e23\u0e2d\u0e1a 10 \u0e1b\u0e35 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e2b\u0e49\u0e2d\u0e07\u0e2a\u0e21\u0e38\u0e14\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e04\u0e1e\u0e35\u0e44\u0e2d\u201d \u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e2b\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e14\u0e47\u0e01\u0e44\u0e17\u0e22\u0e43\u0e2b\u0e49\u0e17\u0e38\u0e19\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e25\u0e2d\u0e14 10 \u0e1b\u0e35 12 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19 - KPI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kpi.co.th\/kpi\/en\/news\/news1\/","og_locale":"en_US","og_type":"article","og_title":"\u0e04\u0e23\u0e1a\u0e23\u0e2d\u0e1a 10 \u0e1b\u0e35 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e2b\u0e49\u0e2d\u0e07\u0e2a\u0e21\u0e38\u0e14\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e04\u0e1e\u0e35\u0e44\u0e2d\u201d \u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e2b\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e14\u0e47\u0e01\u0e44\u0e17\u0e22\u0e43\u0e2b\u0e49\u0e17\u0e38\u0e19\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e25\u0e2d\u0e14 10 \u0e1b\u0e35 12 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19 - KPI","og_description":"\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e04\u0e23\u0e1a\u0e23\u0e2d\u0e1a 10 \u0e1b\u0e35 \u0e2b\u0e49\u0e2d\u0e07\u0e2a\u0e21\u0e38\u0e14\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e04\u0e1e\u0e35\u0e44\u0e2d \u0e41\u0e25\u0e30\u0e1e\u0e34\u0e18\u0e35\u0e21\u0e2d\u0e1a\u0e2b\u0e49\u0e2d\u0e07\u0e2a\u0e21\u0e38\u0e14\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e04\u0e1e\u0e35\u0e44\u0e2d \u0e01\u0e49\u0e32\u0e27\u0e17\u0e35\u0e48\u0e1e\u0e23\u0e49\u0e2d\u0e21 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e40\u0e14\u0e47\u0e01\u0e44\u0e17\u0e22 \u0e41\u0e2b\u0e48\u0e07\u0e17\u0e35\u0e48 12 \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d \u0e08. \u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\u0e04\u0e38\u0e13\u0e2a\u0e38\u0e0a\u0e32\u0e27\u0e14\u0e35 \u0e41\u0e2a\u0e07\u0e2d\u0e19\u0e07\u0e04\u0e4c \u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e0d\u0e48 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e44\u0e17\u0e22\u0e1e\u0e32\u0e19\u0e34\u0e0a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19) \u0e44\u0e14\u0e49\u0e19\u0e33\u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e08\u0e34\u0e15\u0e2d\u0e32\u0e2a\u0e32 \u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e21\u0e32\u0e17\u0e33\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e21\u0e2d\u0e1a\u0e17\u0e38\u0e19\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2b\u0e49\u0e2d\u0e07\u0e2a\u0e21\u0e38\u0e14\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e17\u0e31\u0e49\u0e07 10 \u0e41\u0e2b\u0e48\u0e07 \u0e17\u0e35\u0e48\u0e40\u0e04\u0e22\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2b\u0e49\u0e2d\u0e07\u0e2a\u0e21\u0e38\u0e14\u0e21\u0e32\u0e41\u0e25\u0e49\u0e27 \u0e40\u0e1b\u0e47\u0e19\u0e17\u0e38\u0e19\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e49\u0e19 345,000 \u0e1a\u0e32\u0e17 \u0e41\u0e25\u0e30\u0e21\u0e2d\u0e1a\u0e17\u0e38\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e2d\u0e35\u0e01\u0e08\u0e33\u0e19\u0e27\u0e19 50 \u0e17\u0e38\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e07\u0e34\u0e19 150,000 \u0e1a\u0e32\u0e17\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e19\u0e19\u0e35\u0e49\u0e44\u0e14\u0e49\u0e21\u0e2d\u0e1a\u0e2b\u0e49\u0e2d\u0e07\u0e2a\u0e21\u0e38\u0e14\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e40\u0e04\u0e1e\u0e35\u0e44\u0e2d \u0e41\u0e2b\u0e48\u0e07\u0e17\u0e35\u0e48 12 \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d \u0e08. \u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e17\u0e38\u0e19\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e49\u0e19 450,000 \u0e1a\u0e32\u0e17 \u0e41\u0e25\u0e30\u0e17\u0e38\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2d\u0e35\u0e01\u0e08\u0e33\u0e19\u0e27\u0e19 54 \u0e17\u0e38\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e07\u0e34\u0e19 162,000 \u0e1a\u0e32\u0e17 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 30 \u0e1e\u0e24\u0e28\u0e08\u0e34\u0e01\u0e32\u0e22\u0e19 2566","og_url":"https:\/\/www.kpi.co.th\/kpi\/en\/news\/news1\/","og_site_name":"KPI","article_modified_time":"2024-08-16T07:25:41+00:00","og_image":[{"width":1440,"height":943,"url":"https:\/\/www.kpi.co.th\/wp-content\/uploads\/2024\/01\/001.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.kpi.co.th\/kpi\/en\/news\/news1\/","url":"https:\/\/www.kpi.co.th\/kpi\/en\/news\/news1\/","name":"\u0e04\u0e23\u0e1a\u0e23\u0e2d\u0e1a 10 \u0e1b\u0e35 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e2b\u0e49\u0e2d\u0e07\u0e2a\u0e21\u0e38\u0e14\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e04\u0e1e\u0e35\u0e44\u0e2d\u201d \u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e2b\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e14\u0e47\u0e01\u0e44\u0e17\u0e22\u0e43\u0e2b\u0e49\u0e17\u0e38\u0e19\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e25\u0e2d\u0e14 10 \u0e1b\u0e35 12 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19 - KPI","isPartOf":{"@id":"https:\/\/www.kpi.co.th\/kpi\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kpi.co.th\/kpi\/en\/news\/news1\/#primaryimage"},"image":{"@id":"https:\/\/www.kpi.co.th\/kpi\/en\/news\/news1\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kpi.co.th\/wp-content\/uploads\/2024\/01\/001.jpg","datePublished":"2024-01-16T09:34:02+00:00","dateModified":"2024-08-16T07:25:41+00:00","breadcrumb":{"@id":"https:\/\/www.kpi.co.th\/kpi\/en\/news\/news1\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kpi.co.th\/kpi\/en\/news\/news1\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.kpi.co.th\/kpi\/en\/news\/news1\/#primaryimage","url":"https:\/\/www.kpi.co.th\/wp-content\/uploads\/2024\/01\/001.jpg","contentUrl":"https:\/\/www.kpi.co.th\/wp-content\/uploads\/2024\/01\/001.jpg","width":1440,"height":943},{"@type":"BreadcrumbList","@id":"https:\/\/www.kpi.co.th\/kpi\/en\/news\/news1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kpi.co.th\/kpi\/en\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/www.kpi.co.th\/kpi\/en\/news\/"},{"@type":"ListItem","position":3,"name":"\u0e04\u0e23\u0e1a\u0e23\u0e2d\u0e1a 10 \u0e1b\u0e35 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e2b\u0e49\u0e2d\u0e07\u0e2a\u0e21\u0e38\u0e14\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e04\u0e1e\u0e35\u0e44\u0e2d\u201d \u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e2b\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e14\u0e47\u0e01\u0e44\u0e17\u0e22\u0e43\u0e2b\u0e49\u0e17\u0e38\u0e19\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e25\u0e2d\u0e14 10 \u0e1b\u0e35 12 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19"}]},{"@type":"WebSite","@id":"https:\/\/www.kpi.co.th\/kpi\/en\/#website","url":"https:\/\/www.kpi.co.th\/kpi\/en\/","name":"KPI","description":"KPI","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kpi.co.th\/kpi\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.kpi.co.th\/kpi\/en\/wp-json\/wp\/v2\/news\/13485","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kpi.co.th\/kpi\/en\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/www.kpi.co.th\/kpi\/en\/wp-json\/wp\/v2\/types\/news"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kpi.co.th\/kpi\/en\/wp-json\/wp\/v2\/media\/812"}],"wp:attachment":[{"href":"https:\/\/www.kpi.co.th\/kpi\/en\/wp-json\/wp\/v2\/media?parent=13485"}],"wp:term":[{"taxonomy":"blog_featured","embeddable":true,"href":"https:\/\/www.kpi.co.th\/kpi\/en\/wp-json\/wp\/v2\/blog_featured?post=13485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}