{"id":16817,"date":"2024-03-02T17:37:13","date_gmt":"2024-03-02T10:37:13","guid":{"rendered":"https:\/\/www.kpi.co.th\/kpi\/garage\/%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a2%e0%b8%95%e0%b9%89%e0%b8%b2%e0%b8%9a%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%ad%e0%b8%81-%e0%b8%81%e0%b8%b2%e0%b8%8d%e0%b8%88%e0%b8%99%e0%b8%b2%e0%b8%a0%e0%b8%b4%e0%b9%80\/"},"modified":"2025-09-11T16:24:17","modified_gmt":"2025-09-11T09:24:17","slug":"%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a2%e0%b8%95%e0%b9%89%e0%b8%b2%e0%b8%9a%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%ad%e0%b8%81-%e0%b8%81%e0%b8%b2%e0%b8%8d%e0%b8%88%e0%b8%99%e0%b8%b2%e0%b8%a0%e0%b8%b4%e0%b9%80","status":"publish","type":"garage","link":"https:\/\/www.kpi.co.th\/kpi\/en\/garage\/%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a2%e0%b8%95%e0%b9%89%e0%b8%b2%e0%b8%9a%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%ad%e0%b8%81-%e0%b8%81%e0%b8%b2%e0%b8%8d%e0%b8%88%e0%b8%99%e0%b8%b2%e0%b8%a0%e0%b8%b4%e0%b9%80\/","title":{"rendered":"\u0e42\u0e15\u0e42\u0e22\u0e15\u0e49\u0e32\u0e1a\u0e32\u0e07\u0e01\u0e2d\u0e01 (\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01)"},"content":{"rendered":"\n<p>87\/521-522 \u0e16.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e41\u0e02\u0e27\u0e07\u0e1a\u0e32\u0e07\u0e1a\u0e2d\u0e19 \n \u0e40\u0e02\u0e15\u0e1a\u0e32\u0e07\u0e1a\u0e2d\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 10150<\/p>\n\n","protected":false},"featured_media":0,"template":"","car_type":[],"garage_type":[263,157],"car_brand":[162],"class_list":["post-16817","garage","type-garage","status-publish","hentry","garage_type-all-garage-servicecenter-autoglass-en-2","garage_type-service-center-en","car_brand-toyota-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e42\u0e15\u0e42\u0e22\u0e15\u0e49\u0e32\u0e1a\u0e32\u0e07\u0e01\u0e2d\u0e01 (\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01) - KPI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kpi.co.th\/kpi\/en\/garage\/%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a2%e0%b8%95%e0%b9%89%e0%b8%b2%e0%b8%9a%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%ad%e0%b8%81-%e0%b8%81%e0%b8%b2%e0%b8%8d%e0%b8%88%e0%b8%99%e0%b8%b2%e0%b8%a0%e0%b8%b4%e0%b9%80\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e42\u0e15\u0e42\u0e22\u0e15\u0e49\u0e32\u0e1a\u0e32\u0e07\u0e01\u0e2d\u0e01 (\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01) - KPI\" \/>\n<meta property=\"og:description\" content=\"87\/521-522 \u0e16.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e41\u0e02\u0e27\u0e07\u0e1a\u0e32\u0e07\u0e1a\u0e2d\u0e19 \u0e40\u0e02\u0e15\u0e1a\u0e32\u0e07\u0e1a\u0e2d\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 10150\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kpi.co.th\/kpi\/en\/garage\/%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a2%e0%b8%95%e0%b9%89%e0%b8%b2%e0%b8%9a%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%ad%e0%b8%81-%e0%b8%81%e0%b8%b2%e0%b8%8d%e0%b8%88%e0%b8%99%e0%b8%b2%e0%b8%a0%e0%b8%b4%e0%b9%80\/\" \/>\n<meta property=\"og:site_name\" content=\"KPI\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-11T09:24:17+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/en\\\/garage\\\/%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a2%e0%b8%95%e0%b9%89%e0%b8%b2%e0%b8%9a%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%ad%e0%b8%81-%e0%b8%81%e0%b8%b2%e0%b8%8d%e0%b8%88%e0%b8%99%e0%b8%b2%e0%b8%a0%e0%b8%b4%e0%b9%80\\\/\",\"url\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/en\\\/garage\\\/%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a2%e0%b8%95%e0%b9%89%e0%b8%b2%e0%b8%9a%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%ad%e0%b8%81-%e0%b8%81%e0%b8%b2%e0%b8%8d%e0%b8%88%e0%b8%99%e0%b8%b2%e0%b8%a0%e0%b8%b4%e0%b9%80\\\/\",\"name\":\"\u0e42\u0e15\u0e42\u0e22\u0e15\u0e49\u0e32\u0e1a\u0e32\u0e07\u0e01\u0e2d\u0e01 (\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01) - KPI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/en\\\/#website\"},\"datePublished\":\"2024-03-02T10:37:13+00:00\",\"dateModified\":\"2025-09-11T09:24:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/en\\\/garage\\\/%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a2%e0%b8%95%e0%b9%89%e0%b8%b2%e0%b8%9a%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%ad%e0%b8%81-%e0%b8%81%e0%b8%b2%e0%b8%8d%e0%b8%88%e0%b8%99%e0%b8%b2%e0%b8%a0%e0%b8%b4%e0%b9%80\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/en\\\/garage\\\/%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a2%e0%b8%95%e0%b9%89%e0%b8%b2%e0%b8%9a%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%ad%e0%b8%81-%e0%b8%81%e0%b8%b2%e0%b8%8d%e0%b8%88%e0%b8%99%e0%b8%b2%e0%b8%a0%e0%b8%b4%e0%b9%80\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/en\\\/garage\\\/%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a2%e0%b8%95%e0%b9%89%e0%b8%b2%e0%b8%9a%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%ad%e0%b8%81-%e0%b8%81%e0%b8%b2%e0%b8%8d%e0%b8%88%e0%b8%99%e0%b8%b2%e0%b8%a0%e0%b8%b4%e0%b9%80\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e42\u0e15\u0e42\u0e22\u0e15\u0e49\u0e32\u0e1a\u0e32\u0e07\u0e01\u0e2d\u0e01 (\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/en\\\/\",\"name\":\"KPI\",\"description\":\"KPI\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e42\u0e15\u0e42\u0e22\u0e15\u0e49\u0e32\u0e1a\u0e32\u0e07\u0e01\u0e2d\u0e01 (\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01) - KPI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kpi.co.th\/kpi\/en\/garage\/%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a2%e0%b8%95%e0%b9%89%e0%b8%b2%e0%b8%9a%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%ad%e0%b8%81-%e0%b8%81%e0%b8%b2%e0%b8%8d%e0%b8%88%e0%b8%99%e0%b8%b2%e0%b8%a0%e0%b8%b4%e0%b9%80\/","og_locale":"en_US","og_type":"article","og_title":"\u0e42\u0e15\u0e42\u0e22\u0e15\u0e49\u0e32\u0e1a\u0e32\u0e07\u0e01\u0e2d\u0e01 (\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01) - KPI","og_description":"87\/521-522 \u0e16.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e41\u0e02\u0e27\u0e07\u0e1a\u0e32\u0e07\u0e1a\u0e2d\u0e19 \u0e40\u0e02\u0e15\u0e1a\u0e32\u0e07\u0e1a\u0e2d\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 10150","og_url":"https:\/\/www.kpi.co.th\/kpi\/en\/garage\/%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a2%e0%b8%95%e0%b9%89%e0%b8%b2%e0%b8%9a%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%ad%e0%b8%81-%e0%b8%81%e0%b8%b2%e0%b8%8d%e0%b8%88%e0%b8%99%e0%b8%b2%e0%b8%a0%e0%b8%b4%e0%b9%80\/","og_site_name":"KPI","article_modified_time":"2025-09-11T09:24:17+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.kpi.co.th\/kpi\/en\/garage\/%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a2%e0%b8%95%e0%b9%89%e0%b8%b2%e0%b8%9a%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%ad%e0%b8%81-%e0%b8%81%e0%b8%b2%e0%b8%8d%e0%b8%88%e0%b8%99%e0%b8%b2%e0%b8%a0%e0%b8%b4%e0%b9%80\/","url":"https:\/\/www.kpi.co.th\/kpi\/en\/garage\/%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a2%e0%b8%95%e0%b9%89%e0%b8%b2%e0%b8%9a%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%ad%e0%b8%81-%e0%b8%81%e0%b8%b2%e0%b8%8d%e0%b8%88%e0%b8%99%e0%b8%b2%e0%b8%a0%e0%b8%b4%e0%b9%80\/","name":"\u0e42\u0e15\u0e42\u0e22\u0e15\u0e49\u0e32\u0e1a\u0e32\u0e07\u0e01\u0e2d\u0e01 (\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01) - KPI","isPartOf":{"@id":"https:\/\/www.kpi.co.th\/kpi\/en\/#website"},"datePublished":"2024-03-02T10:37:13+00:00","dateModified":"2025-09-11T09:24:17+00:00","breadcrumb":{"@id":"https:\/\/www.kpi.co.th\/kpi\/en\/garage\/%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a2%e0%b8%95%e0%b9%89%e0%b8%b2%e0%b8%9a%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%ad%e0%b8%81-%e0%b8%81%e0%b8%b2%e0%b8%8d%e0%b8%88%e0%b8%99%e0%b8%b2%e0%b8%a0%e0%b8%b4%e0%b9%80\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kpi.co.th\/kpi\/en\/garage\/%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a2%e0%b8%95%e0%b9%89%e0%b8%b2%e0%b8%9a%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%ad%e0%b8%81-%e0%b8%81%e0%b8%b2%e0%b8%8d%e0%b8%88%e0%b8%99%e0%b8%b2%e0%b8%a0%e0%b8%b4%e0%b9%80\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.kpi.co.th\/kpi\/en\/garage\/%e0%b9%82%e0%b8%95%e0%b9%82%e0%b8%a2%e0%b8%95%e0%b9%89%e0%b8%b2%e0%b8%9a%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%ad%e0%b8%81-%e0%b8%81%e0%b8%b2%e0%b8%8d%e0%b8%88%e0%b8%99%e0%b8%b2%e0%b8%a0%e0%b8%b4%e0%b9%80\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kpi.co.th\/kpi\/en\/"},{"@type":"ListItem","position":2,"name":"\u0e42\u0e15\u0e42\u0e22\u0e15\u0e49\u0e32\u0e1a\u0e32\u0e07\u0e01\u0e2d\u0e01 (\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01)"}]},{"@type":"WebSite","@id":"https:\/\/www.kpi.co.th\/kpi\/en\/#website","url":"https:\/\/www.kpi.co.th\/kpi\/en\/","name":"KPI","description":"KPI","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kpi.co.th\/kpi\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.kpi.co.th\/kpi\/en\/wp-json\/wp\/v2\/garage\/16817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kpi.co.th\/kpi\/en\/wp-json\/wp\/v2\/garage"}],"about":[{"href":"https:\/\/www.kpi.co.th\/kpi\/en\/wp-json\/wp\/v2\/types\/garage"}],"wp:attachment":[{"href":"https:\/\/www.kpi.co.th\/kpi\/en\/wp-json\/wp\/v2\/media?parent=16817"}],"wp:term":[{"taxonomy":"car_type","embeddable":true,"href":"https:\/\/www.kpi.co.th\/kpi\/en\/wp-json\/wp\/v2\/car_type?post=16817"},{"taxonomy":"garage_type","embeddable":true,"href":"https:\/\/www.kpi.co.th\/kpi\/en\/wp-json\/wp\/v2\/garage_type?post=16817"},{"taxonomy":"car_brand","embeddable":true,"href":"https:\/\/www.kpi.co.th\/kpi\/en\/wp-json\/wp\/v2\/car_brand?post=16817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}