{"id":16728,"date":"2024-03-02T17:37:04","date_gmt":"2024-03-02T10:37:04","guid":{"rendered":"https:\/\/www.kpi.co.th\/kpi\/garage\/%e0%b9%80%e0%b8%ad%e0%b9%87%e0%b8%99-%e0%b8%8b%e0%b8%b5-%e0%b9%80%e0%b8%ad%e0%b9%87%e0%b8%a1-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%89-%e0%b9%80%e0%b8%8b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b8%a7\/"},"modified":"2025-09-11T14:04:59","modified_gmt":"2025-09-11T07:04:59","slug":"%e0%b9%80%e0%b8%ad%e0%b9%87%e0%b8%99-%e0%b8%8b%e0%b8%b5-%e0%b9%80%e0%b8%ad%e0%b9%87%e0%b8%a1-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%89-%e0%b9%80%e0%b8%8b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b8%a7","status":"publish","type":"garage","link":"https:\/\/www.kpi.co.th\/kpi\/en\/garage\/%e0%b9%80%e0%b8%ad%e0%b9%87%e0%b8%99-%e0%b8%8b%e0%b8%b5-%e0%b9%80%e0%b8%ad%e0%b9%87%e0%b8%a1-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%89-%e0%b9%80%e0%b8%8b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b8%a7\/","title":{"rendered":"\u0e40\u0e2d\u0e47\u0e19 \u0e0b\u0e35 \u0e40\u0e2d\u0e47\u0e21 \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a"},"content":{"rendered":"\n<p>17\/45-46 \u0e2b\u0e21\u0e39\u0e48 2 \u0e16.\u0e08\u0e2d\u0e21\u0e17\u0e2d\u0e07 \u0e41\u0e02\u0e27\u0e07\u0e08\u0e2d\u0e21\u0e17\u0e2d\u0e07 \n \u0e40\u0e02\u0e15\u0e08\u0e2d\u0e21\u0e17\u0e2d\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 10150<\/p>\n\n\n\n<p><\/p>\n","protected":false},"featured_media":0,"template":"","car_type":[],"garage_type":[263,157],"car_brand":[193],"class_list":["post-16728","garage","type-garage","status-publish","hentry","garage_type-all-garage-servicecenter-autoglass-en-2","garage_type-service-center-en","car_brand--en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e40\u0e2d\u0e47\u0e19 \u0e0b\u0e35 \u0e40\u0e2d\u0e47\u0e21 \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a - KPI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kpi.co.th\/kpi\/en\/garage\/%e0%b9%80%e0%b8%ad%e0%b9%87%e0%b8%99-%e0%b8%8b%e0%b8%b5-%e0%b9%80%e0%b8%ad%e0%b9%87%e0%b8%a1-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%89-%e0%b9%80%e0%b8%8b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b8%a7\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e40\u0e2d\u0e47\u0e19 \u0e0b\u0e35 \u0e40\u0e2d\u0e47\u0e21 \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a - KPI\" \/>\n<meta property=\"og:description\" content=\"17\/45-46 \u0e2b\u0e21\u0e39\u0e48 2 \u0e16.\u0e08\u0e2d\u0e21\u0e17\u0e2d\u0e07 \u0e41\u0e02\u0e27\u0e07\u0e08\u0e2d\u0e21\u0e17\u0e2d\u0e07 \u0e40\u0e02\u0e15\u0e08\u0e2d\u0e21\u0e17\u0e2d\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 10150\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kpi.co.th\/kpi\/en\/garage\/%e0%b9%80%e0%b8%ad%e0%b9%87%e0%b8%99-%e0%b8%8b%e0%b8%b5-%e0%b9%80%e0%b8%ad%e0%b9%87%e0%b8%a1-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%89-%e0%b9%80%e0%b8%8b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b8%a7\/\" \/>\n<meta property=\"og:site_name\" content=\"KPI\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-11T07:04:59+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/en\\\/garage\\\/%e0%b9%80%e0%b8%ad%e0%b9%87%e0%b8%99-%e0%b8%8b%e0%b8%b5-%e0%b9%80%e0%b8%ad%e0%b9%87%e0%b8%a1-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%89-%e0%b9%80%e0%b8%8b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b8%a7\\\/\",\"url\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/en\\\/garage\\\/%e0%b9%80%e0%b8%ad%e0%b9%87%e0%b8%99-%e0%b8%8b%e0%b8%b5-%e0%b9%80%e0%b8%ad%e0%b9%87%e0%b8%a1-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%89-%e0%b9%80%e0%b8%8b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b8%a7\\\/\",\"name\":\"\u0e40\u0e2d\u0e47\u0e19 \u0e0b\u0e35 \u0e40\u0e2d\u0e47\u0e21 \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a - KPI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/en\\\/#website\"},\"datePublished\":\"2024-03-02T10:37:04+00:00\",\"dateModified\":\"2025-09-11T07:04:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/en\\\/garage\\\/%e0%b9%80%e0%b8%ad%e0%b9%87%e0%b8%99-%e0%b8%8b%e0%b8%b5-%e0%b9%80%e0%b8%ad%e0%b9%87%e0%b8%a1-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%89-%e0%b9%80%e0%b8%8b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b8%a7\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/en\\\/garage\\\/%e0%b9%80%e0%b8%ad%e0%b9%87%e0%b8%99-%e0%b8%8b%e0%b8%b5-%e0%b9%80%e0%b8%ad%e0%b9%87%e0%b8%a1-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%89-%e0%b9%80%e0%b8%8b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b8%a7\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/en\\\/garage\\\/%e0%b9%80%e0%b8%ad%e0%b9%87%e0%b8%99-%e0%b8%8b%e0%b8%b5-%e0%b9%80%e0%b8%ad%e0%b9%87%e0%b8%a1-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%89-%e0%b9%80%e0%b8%8b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b8%a7\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e40\u0e2d\u0e47\u0e19 \u0e0b\u0e35 \u0e40\u0e2d\u0e47\u0e21 \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/en\\\/\",\"name\":\"KPI\",\"description\":\"KPI\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kpi.co.th\\\/kpi\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e40\u0e2d\u0e47\u0e19 \u0e0b\u0e35 \u0e40\u0e2d\u0e47\u0e21 \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a - KPI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kpi.co.th\/kpi\/en\/garage\/%e0%b9%80%e0%b8%ad%e0%b9%87%e0%b8%99-%e0%b8%8b%e0%b8%b5-%e0%b9%80%e0%b8%ad%e0%b9%87%e0%b8%a1-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%89-%e0%b9%80%e0%b8%8b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b8%a7\/","og_locale":"en_US","og_type":"article","og_title":"\u0e40\u0e2d\u0e47\u0e19 \u0e0b\u0e35 \u0e40\u0e2d\u0e47\u0e21 \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a - KPI","og_description":"17\/45-46 \u0e2b\u0e21\u0e39\u0e48 2 \u0e16.\u0e08\u0e2d\u0e21\u0e17\u0e2d\u0e07 \u0e41\u0e02\u0e27\u0e07\u0e08\u0e2d\u0e21\u0e17\u0e2d\u0e07 \u0e40\u0e02\u0e15\u0e08\u0e2d\u0e21\u0e17\u0e2d\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 10150","og_url":"https:\/\/www.kpi.co.th\/kpi\/en\/garage\/%e0%b9%80%e0%b8%ad%e0%b9%87%e0%b8%99-%e0%b8%8b%e0%b8%b5-%e0%b9%80%e0%b8%ad%e0%b9%87%e0%b8%a1-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%89-%e0%b9%80%e0%b8%8b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b8%a7\/","og_site_name":"KPI","article_modified_time":"2025-09-11T07:04:59+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.kpi.co.th\/kpi\/en\/garage\/%e0%b9%80%e0%b8%ad%e0%b9%87%e0%b8%99-%e0%b8%8b%e0%b8%b5-%e0%b9%80%e0%b8%ad%e0%b9%87%e0%b8%a1-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%89-%e0%b9%80%e0%b8%8b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b8%a7\/","url":"https:\/\/www.kpi.co.th\/kpi\/en\/garage\/%e0%b9%80%e0%b8%ad%e0%b9%87%e0%b8%99-%e0%b8%8b%e0%b8%b5-%e0%b9%80%e0%b8%ad%e0%b9%87%e0%b8%a1-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%89-%e0%b9%80%e0%b8%8b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b8%a7\/","name":"\u0e40\u0e2d\u0e47\u0e19 \u0e0b\u0e35 \u0e40\u0e2d\u0e47\u0e21 \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a - KPI","isPartOf":{"@id":"https:\/\/www.kpi.co.th\/kpi\/en\/#website"},"datePublished":"2024-03-02T10:37:04+00:00","dateModified":"2025-09-11T07:04:59+00:00","breadcrumb":{"@id":"https:\/\/www.kpi.co.th\/kpi\/en\/garage\/%e0%b9%80%e0%b8%ad%e0%b9%87%e0%b8%99-%e0%b8%8b%e0%b8%b5-%e0%b9%80%e0%b8%ad%e0%b9%87%e0%b8%a1-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%89-%e0%b9%80%e0%b8%8b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b8%a7\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kpi.co.th\/kpi\/en\/garage\/%e0%b9%80%e0%b8%ad%e0%b9%87%e0%b8%99-%e0%b8%8b%e0%b8%b5-%e0%b9%80%e0%b8%ad%e0%b9%87%e0%b8%a1-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%89-%e0%b9%80%e0%b8%8b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b8%a7\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.kpi.co.th\/kpi\/en\/garage\/%e0%b9%80%e0%b8%ad%e0%b9%87%e0%b8%99-%e0%b8%8b%e0%b8%b5-%e0%b9%80%e0%b8%ad%e0%b9%87%e0%b8%a1-%e0%b8%ad%e0%b8%ad%e0%b9%82%e0%b8%95%e0%b9%89-%e0%b9%80%e0%b8%8b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b8%a7\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kpi.co.th\/kpi\/en\/"},{"@type":"ListItem","position":2,"name":"\u0e40\u0e2d\u0e47\u0e19 \u0e0b\u0e35 \u0e40\u0e2d\u0e47\u0e21 \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a"}]},{"@type":"WebSite","@id":"https:\/\/www.kpi.co.th\/kpi\/en\/#website","url":"https:\/\/www.kpi.co.th\/kpi\/en\/","name":"KPI","description":"KPI","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kpi.co.th\/kpi\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.kpi.co.th\/kpi\/en\/wp-json\/wp\/v2\/garage\/16728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kpi.co.th\/kpi\/en\/wp-json\/wp\/v2\/garage"}],"about":[{"href":"https:\/\/www.kpi.co.th\/kpi\/en\/wp-json\/wp\/v2\/types\/garage"}],"wp:attachment":[{"href":"https:\/\/www.kpi.co.th\/kpi\/en\/wp-json\/wp\/v2\/media?parent=16728"}],"wp:term":[{"taxonomy":"car_type","embeddable":true,"href":"https:\/\/www.kpi.co.th\/kpi\/en\/wp-json\/wp\/v2\/car_type?post=16728"},{"taxonomy":"garage_type","embeddable":true,"href":"https:\/\/www.kpi.co.th\/kpi\/en\/wp-json\/wp\/v2\/garage_type?post=16728"},{"taxonomy":"car_brand","embeddable":true,"href":"https:\/\/www.kpi.co.th\/kpi\/en\/wp-json\/wp\/v2\/car_brand?post=16728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}